{"id":445,"date":"2019-09-18T07:35:23","date_gmt":"2019-09-18T07:35:23","guid":{"rendered":"https:\/\/www.adiccionmalaga.com\/?page_id=445"},"modified":"2023-09-07T13:54:04","modified_gmt":"2023-09-07T13:54:04","slug":"actualidad","status":"publish","type":"page","link":"https:\/\/forummontau.com\/malaga\/actualidad\/","title":{"rendered":"Actualidad"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"445\" class=\"elementor elementor-445\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d5c81bf elementor-section-boxed elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"d5c81bf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5872b96\" data-id=\"5872b96\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-172a533 elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-widget elementor-widget-posts\" data-id=\"172a533\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;pagination_type&quot;:&quot;prev_next&quot;,&quot;classic_columns&quot;:&quot;3&quot;,&quot;classic_columns_tablet&quot;:&quot;2&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2787 post type-post status-publish format-standard has-post-thumbnail hentry category-adicciones category-compras-compulsivas tag-centro-especializado-en-adicciones tag-forum-malaga entry has-media\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/forummontau.com\/malaga\/adiccion-a-las-compras-cuando-el-consumo-se-convierte-en-un-problema\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/forummontau.com\/malaga\/wp-content\/uploads\/sites\/11\/2025\/11\/adiccion-compras-1-1-300x200.webp\" class=\"attachment-medium size-medium wp-image-3339\" alt=\"COmpras compulsiva\" srcset=\"https:\/\/forummontau.com\/malaga\/wp-content\/uploads\/sites\/11\/2025\/11\/adiccion-compras-1-1-300x200.webp 300w, https:\/\/forummontau.com\/malaga\/wp-content\/uploads\/sites\/11\/2025\/11\/adiccion-compras-1-1-768x512.webp 768w, https:\/\/forummontau.com\/malaga\/wp-content\/uploads\/sites\/11\/2025\/11\/adiccion-compras-1-1.webp 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/forummontau.com\/malaga\/adiccion-a-las-compras-cuando-el-consumo-se-convierte-en-un-problema\/\" >\n\t\t\t\tAdicci\u00f3n a las compras: Cuando el consumo se convierte en un problema\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t18\/11\/2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>1. El auge del consumismo en fechas se\u00f1aladas Con la llegada de eventos como el Black Friday, Cyber Monday, Navidad o las tradicionales rebajas de<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/forummontau.com\/malaga\/adiccion-a-las-compras-cuando-el-consumo-se-convierte-en-un-problema\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre Adicci\u00f3n a las compras: Cuando el consumo se convierte en un problema\" tabindex=\"-1\" >\n\t\t\tLeer M\u00e1s &gt;&gt;\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-491 post type-post status-publish format-standard has-post-thumbnail hentry category-adicciones category-drogas category-familia tag-forum-malaga entry has-media\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/forummontau.com\/malaga\/la-familia-y-el-entorno-del-adicto-claves-para-su-recuperacion\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/forummontau.com\/malaga\/wp-content\/uploads\/sites\/11\/2020\/09\/recuperacion-adicciones-y-familia-300x200.webp\" class=\"attachment-medium size-medium wp-image-3327\" alt=\"Recuperaci\u00f3n adicciones y familia\" srcset=\"https:\/\/forummontau.com\/malaga\/wp-content\/uploads\/sites\/11\/2020\/09\/recuperacion-adicciones-y-familia-300x200.webp 300w, https:\/\/forummontau.com\/malaga\/wp-content\/uploads\/sites\/11\/2020\/09\/recuperacion-adicciones-y-familia-768x512.webp 768w, https:\/\/forummontau.com\/malaga\/wp-content\/uploads\/sites\/11\/2020\/09\/recuperacion-adicciones-y-familia.webp 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/forummontau.com\/malaga\/la-familia-y-el-entorno-del-adicto-claves-para-su-recuperacion\/\" >\n\t\t\t\tLa familia y el entorno del adicto, claves para su recuperaci\u00f3n\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t17\/09\/2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Cuando una persona consume sustancias, no solo sufre ella, sino tambi\u00e9n su familia y su entorno cercano. Por ello, en el momento en que la<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/forummontau.com\/malaga\/la-familia-y-el-entorno-del-adicto-claves-para-su-recuperacion\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre La familia y el entorno del adicto, claves para su recuperaci\u00f3n\" tabindex=\"-1\" >\n\t\t\tLeer M\u00e1s &gt;&gt;\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-3306 post type-post status-publish format-aside has-post-thumbnail hentry category-adiccion category-cannabiodes category-cannabis-sintetico category-spiece tag-forum-malaga post_format-post-format-aside entry has-media\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/forummontau.com\/malaga\/adiccion-a-cannabinoides-sinteticos-efectos-reales-riesgos-invisibles\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/forummontau.com\/malaga\/wp-content\/uploads\/sites\/11\/2025\/05\/cannabiodes-sinteticos-riesgos-malaga-300x200.webp\" class=\"attachment-medium size-medium wp-image-3307\" alt=\"Cannabiodes sint\u00e9ticos\" srcset=\"https:\/\/forummontau.com\/malaga\/wp-content\/uploads\/sites\/11\/2025\/05\/cannabiodes-sinteticos-riesgos-malaga-300x200.webp 300w, https:\/\/forummontau.com\/malaga\/wp-content\/uploads\/sites\/11\/2025\/05\/cannabiodes-sinteticos-riesgos-malaga-768x512.webp 768w, https:\/\/forummontau.com\/malaga\/wp-content\/uploads\/sites\/11\/2025\/05\/cannabiodes-sinteticos-riesgos-malaga.webp 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/forummontau.com\/malaga\/adiccion-a-cannabinoides-sinteticos-efectos-reales-riesgos-invisibles\/\" >\n\t\t\t\tAdicci\u00f3n a cannabinoides sint\u00e9ticos: efectos reales, riesgos invisibles\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t19\/05\/2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Los cannabinoides sint\u00e9ticos son una categor\u00eda de sustancias psicoactivas que forman parte del grupo de las nuevas sustancias psicoactivas (NSP). A diferencia del cannabis natural,<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/forummontau.com\/malaga\/adiccion-a-cannabinoides-sinteticos-efectos-reales-riesgos-invisibles\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre Adicci\u00f3n a cannabinoides sint\u00e9ticos: efectos reales, riesgos invisibles\" tabindex=\"-1\" >\n\t\t\tLeer M\u00e1s &gt;&gt;\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-3288 post type-post status-publish format-aside has-post-thumbnail hentry category-adiccion category-insomnio tag-centro-de-adicciones-malaga tag-forum-malaga post_format-post-format-aside entry has-media\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/forummontau.com\/malaga\/insomnio-y-adicciones-como-afecta-la-falta-de-sueno-a-la-salud-mental\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/forummontau.com\/malaga\/wp-content\/uploads\/sites\/11\/2025\/04\/insomnio-y-adicciones-malaga-300x200.webp\" class=\"attachment-medium size-medium wp-image-3289\" alt=\"Insomnio y adicciones M\u00e1laga\" srcset=\"https:\/\/forummontau.com\/malaga\/wp-content\/uploads\/sites\/11\/2025\/04\/insomnio-y-adicciones-malaga-300x200.webp 300w, https:\/\/forummontau.com\/malaga\/wp-content\/uploads\/sites\/11\/2025\/04\/insomnio-y-adicciones-malaga-768x512.webp 768w, https:\/\/forummontau.com\/malaga\/wp-content\/uploads\/sites\/11\/2025\/04\/insomnio-y-adicciones-malaga.webp 1001w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/forummontau.com\/malaga\/insomnio-y-adicciones-como-afecta-la-falta-de-sueno-a-la-salud-mental\/\" >\n\t\t\t\tInsomnio y adicciones: \u00bfC\u00f3mo afecta la falta de sue\u00f1o a la salud mental?\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t29\/04\/2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>En Forum Salud Mental M\u00e1laga, sabemos que el sue\u00f1o es uno de los pilares esenciales para mantener una buena salud mental. Sin embargo, en la<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/forummontau.com\/malaga\/insomnio-y-adicciones-como-afecta-la-falta-de-sueno-a-la-salud-mental\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre Insomnio y adicciones: \u00bfC\u00f3mo afecta la falta de sue\u00f1o a la salud mental?\" tabindex=\"-1\" >\n\t\t\tLeer M\u00e1s &gt;&gt;\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-3277 post type-post status-publish format-aside has-post-thumbnail hentry category-adiccion category-microbiota category-tratamientos tag-forum-malaga post_format-post-format-aside entry has-media\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/forummontau.com\/malaga\/relacion-intestino-cerebro-y-adiccion-puede-la-microbiota-modular-el-deseo-de-consumo\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/forummontau.com\/malaga\/wp-content\/uploads\/sites\/11\/2025\/02\/microbiota-adicciones-300x200.webp\" class=\"attachment-medium size-medium wp-image-3278\" alt=\"\" srcset=\"https:\/\/forummontau.com\/malaga\/wp-content\/uploads\/sites\/11\/2025\/02\/microbiota-adicciones-300x200.webp 300w, https:\/\/forummontau.com\/malaga\/wp-content\/uploads\/sites\/11\/2025\/02\/microbiota-adicciones-768x512.webp 768w, https:\/\/forummontau.com\/malaga\/wp-content\/uploads\/sites\/11\/2025\/02\/microbiota-adicciones.webp 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/forummontau.com\/malaga\/relacion-intestino-cerebro-y-adiccion-puede-la-microbiota-modular-el-deseo-de-consumo\/\" >\n\t\t\t\tRelaci\u00f3n Intestino-Cerebro y adicci\u00f3n: \u00bfpuede la microbiota modular el deseo de consumo?\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t18\/02\/2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>En los \u00faltimos a\u00f1os, la ciencia ha revelado una conexi\u00f3n profunda entre el intestino y el cerebro, conocida como el eje intestino-cerebro. Este v\u00ednculo no<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/forummontau.com\/malaga\/relacion-intestino-cerebro-y-adiccion-puede-la-microbiota-modular-el-deseo-de-consumo\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre Relaci\u00f3n Intestino-Cerebro y adicci\u00f3n: \u00bfpuede la microbiota modular el deseo de consumo?\" tabindex=\"-1\" >\n\t\t\tLeer M\u00e1s &gt;&gt;\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-3261 post type-post status-publish format-aside has-post-thumbnail hentry category-adiccion category-policonsumo category-tratamientos tag-forum-malaga post_format-post-format-aside entry has-media\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/forummontau.com\/malaga\/policonsumo-en-malaga-un-peligro-oculto-que-crece-entre-los-jovenes\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/forummontau.com\/malaga\/wp-content\/uploads\/sites\/11\/2024\/11\/policonsumo-malaga-300x200.webp\" class=\"attachment-medium size-medium wp-image-3262\" alt=\"\" srcset=\"https:\/\/forummontau.com\/malaga\/wp-content\/uploads\/sites\/11\/2024\/11\/policonsumo-malaga-300x200.webp 300w, https:\/\/forummontau.com\/malaga\/wp-content\/uploads\/sites\/11\/2024\/11\/policonsumo-malaga-768x512.webp 768w, https:\/\/forummontau.com\/malaga\/wp-content\/uploads\/sites\/11\/2024\/11\/policonsumo-malaga.webp 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/forummontau.com\/malaga\/policonsumo-en-malaga-un-peligro-oculto-que-crece-entre-los-jovenes\/\" >\n\t\t\t\tPoliconsumo en M\u00e1laga: Un peligro oculto que crece entre los J\u00f3venes\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t14\/11\/2024\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>En M\u00e1laga, al igual que en otras regiones de Espa\u00f1a, el consumo de m\u00faltiples sustancias de forma simult\u00e1nea o secuencial, conocido como policonsumo, se est\u00e1<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/forummontau.com\/malaga\/policonsumo-en-malaga-un-peligro-oculto-que-crece-entre-los-jovenes\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre Policonsumo en M\u00e1laga: Un peligro oculto que crece entre los J\u00f3venes\" tabindex=\"-1\" >\n\t\t\tLeer M\u00e1s &gt;&gt;\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t<div class=\"e-load-more-anchor\" data-page=\"1\" data-max-page=\"8\" data-next-page=\"https:\/\/forummontau.com\/malaga\/wp-json\/wp\/v2\/pages\/445\/page\/2\/\"><\/div>\n\t\t\t\t<nav class=\"elementor-pagination\" aria-label=\"Paginaci\u00f3n\">\n\t\t\t<span class=\"page-numbers prev\">&laquo; Anterior<\/span>\n<a class=\"page-numbers next\" href=\"https:\/\/forummontau.com\/malaga\/wp-json\/wp\/v2\/pages\/445\/page\/2\/\">Siguiente&raquo;<\/a>\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ocean_front_end_style_editor":"no","ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"on","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","footnotes":""},"class_list":["post-445","page","type-page","status-publish","hentry","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Actualidad - Forum Salud Mental M\u00e1laga<\/title>\n<meta name=\"description\" content=\"En el siguiente blog encontrar\u00e1 toda la informaci\u00f3n relacionada con la salud mental y las adicciones a sustancia y\/o comportamentales.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/forummontau.com\/malaga\/actualidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Actualidad - Forum Salud Mental M\u00e1laga\" \/>\n<meta property=\"og:description\" content=\"En el siguiente blog encontrar\u00e1 toda la informaci\u00f3n relacionada con la salud mental y las adicciones a sustancia y\/o comportamentales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/forummontau.com\/malaga\/actualidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Forum Salud Mental M\u00e1laga\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-07T13:54:04+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/forummontau.com\\\/malaga\\\/actualidad\\\/\",\"url\":\"https:\\\/\\\/forummontau.com\\\/malaga\\\/actualidad\\\/\",\"name\":\"Actualidad - Forum Salud Mental M\u00e1laga\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/forummontau.com\\\/malaga\\\/#website\"},\"datePublished\":\"2019-09-18T07:35:23+00:00\",\"dateModified\":\"2023-09-07T13:54:04+00:00\",\"description\":\"En el siguiente blog encontrar\u00e1 toda la informaci\u00f3n relacionada con la salud mental y las adicciones a sustancia y\\\/o comportamentales.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/forummontau.com\\\/malaga\\\/actualidad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/forummontau.com\\\/malaga\\\/actualidad\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/forummontau.com\\\/malaga\\\/actualidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/forummontau.com\\\/malaga\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Actualidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/forummontau.com\\\/malaga\\\/#website\",\"url\":\"https:\\\/\\\/forummontau.com\\\/malaga\\\/\",\"name\":\"Forum Salud Mental M\u00e1laga\",\"description\":\"Centro Tratamiento Adicciones\",\"publisher\":{\"@id\":\"https:\\\/\\\/forummontau.com\\\/malaga\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/forummontau.com\\\/malaga\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/forummontau.com\\\/malaga\\\/#organization\",\"name\":\"Forum Salud Mental M\u00e1laga\",\"url\":\"https:\\\/\\\/forummontau.com\\\/malaga\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/forummontau.com\\\/malaga\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/forummontau.com\\\/malaga\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2026\\\/08\\\/logo-forum-malaga.png\",\"contentUrl\":\"https:\\\/\\\/forummontau.com\\\/malaga\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2026\\\/08\\\/logo-forum-malaga.png\",\"width\":215,\"height\":123,\"caption\":\"Forum Salud Mental M\u00e1laga\"},\"image\":{\"@id\":\"https:\\\/\\\/forummontau.com\\\/malaga\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Actualidad - Forum Salud Mental M\u00e1laga","description":"En el siguiente blog encontrar\u00e1 toda la informaci\u00f3n relacionada con la salud mental y las adicciones a sustancia y\/o comportamentales.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/forummontau.com\/malaga\/actualidad\/","og_locale":"es_ES","og_type":"article","og_title":"Actualidad - Forum Salud Mental M\u00e1laga","og_description":"En el siguiente blog encontrar\u00e1 toda la informaci\u00f3n relacionada con la salud mental y las adicciones a sustancia y\/o comportamentales.","og_url":"https:\/\/forummontau.com\/malaga\/actualidad\/","og_site_name":"Forum Salud Mental M\u00e1laga","article_modified_time":"2023-09-07T13:54:04+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/forummontau.com\/malaga\/actualidad\/","url":"https:\/\/forummontau.com\/malaga\/actualidad\/","name":"Actualidad - Forum Salud Mental M\u00e1laga","isPartOf":{"@id":"https:\/\/forummontau.com\/malaga\/#website"},"datePublished":"2019-09-18T07:35:23+00:00","dateModified":"2023-09-07T13:54:04+00:00","description":"En el siguiente blog encontrar\u00e1 toda la informaci\u00f3n relacionada con la salud mental y las adicciones a sustancia y\/o comportamentales.","breadcrumb":{"@id":"https:\/\/forummontau.com\/malaga\/actualidad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/forummontau.com\/malaga\/actualidad\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/forummontau.com\/malaga\/actualidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/forummontau.com\/malaga\/"},{"@type":"ListItem","position":2,"name":"Actualidad"}]},{"@type":"WebSite","@id":"https:\/\/forummontau.com\/malaga\/#website","url":"https:\/\/forummontau.com\/malaga\/","name":"Forum Salud Mental M\u00e1laga","description":"Centro Tratamiento Adicciones","publisher":{"@id":"https:\/\/forummontau.com\/malaga\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/forummontau.com\/malaga\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/forummontau.com\/malaga\/#organization","name":"Forum Salud Mental M\u00e1laga","url":"https:\/\/forummontau.com\/malaga\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/forummontau.com\/malaga\/#\/schema\/logo\/image\/","url":"https:\/\/forummontau.com\/malaga\/wp-content\/uploads\/sites\/11\/2026\/08\/logo-forum-malaga.png","contentUrl":"https:\/\/forummontau.com\/malaga\/wp-content\/uploads\/sites\/11\/2026\/08\/logo-forum-malaga.png","width":215,"height":123,"caption":"Forum Salud Mental M\u00e1laga"},"image":{"@id":"https:\/\/forummontau.com\/malaga\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/forummontau.com\/malaga\/wp-json\/wp\/v2\/pages\/445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forummontau.com\/malaga\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/forummontau.com\/malaga\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/forummontau.com\/malaga\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/forummontau.com\/malaga\/wp-json\/wp\/v2\/comments?post=445"}],"version-history":[{"count":12,"href":"https:\/\/forummontau.com\/malaga\/wp-json\/wp\/v2\/pages\/445\/revisions"}],"predecessor-version":[{"id":3031,"href":"https:\/\/forummontau.com\/malaga\/wp-json\/wp\/v2\/pages\/445\/revisions\/3031"}],"wp:attachment":[{"href":"https:\/\/forummontau.com\/malaga\/wp-json\/wp\/v2\/media?parent=445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}